{"id":515,"date":"2019-02-26T18:51:03","date_gmt":"2019-02-26T18:51:03","guid":{"rendered":"http:\/\/wintersport.news\/?p=515"},"modified":"2019-02-27T06:55:20","modified_gmt":"2019-02-27T06:55:20","slug":"wm-seefeld-2019-zweites-gold-fuer-johaug-russlands-damen-gehen-leer-aus","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/wm-seefeld-2019-zweites-gold-fuer-johaug-russlands-damen-gehen-leer-aus\/","title":{"rendered":"WM Seefeld 2019: Zweites Gold f\u00fcr Johaug &#8211; Russlands Damen gehen leer aus"},"content":{"rendered":"<p>Wer will diese Therese Johaug eigentlich bei der WM in Seefeld schlagen? Unter den Augen des Norwegischen K\u00f6nigs Harald , aber auch unter denen des Schwedischen K\u00f6nigs Carl &#8211; Gustav l\u00e4uft Therese Johaug erneut zu Gold,und gewinnt auch die 10 Km Individal im klassischen Stil der Damen, und damit ihre zweite Goldmedaille. Die Silbermedaille ging nach einer super Leistung an die junge Schwedin Frida Karlsson, die lange gef\u00fchrt hatte.Die Bronzemedaille holte sich Ingvild Flugstad Oestberg. Keine Medaillen gab es hingegen f\u00fcr die Russischen L\u00e4uferinnen. Anastasia Sedova belegte mit einem R\u00fcckstand von 1.04,9 Minuten Platz sechs, Natalia Nepryaeva mit einem R\u00fcckstand von 1.07,5 Minuten Platz sieben und Yulia Belorukova \u00a0mit einem R\u00fcckstand von 1.17,0 Minuten den zw\u00f6lften Platz.<\/p>\n<p>Ergebnisse WM Seefeld 10 Km Individual Klassisch Damen:<\/p>\n<ol>\n<li>Therese Johaug, NOR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 27.02,1 Min.<\/li>\n<li>Frida Karlsson, SWE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 + 12,2 Sek.<\/li>\n<li>Ingvild Flugstad Oestberg, NOR \u00a0 + 35,6 Min.<\/li>\n<\/ol>\n<p>.<\/p>\n<ol start=\"6\">\n<li>Anastasia Sedova, RUS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 + 1.04,9 Min.<\/li>\n<li>Natalia Nepryaeva, RUS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 + 1.07,5 Min.<\/li>\n<li>Yulia Belorukova, RUS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0+ 1.17,0 Min.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<blockquote><p>Es war beim Einlaufen schon eine Wahnsinnsstimmung im Stadion, und diese tollen Fans haben mich heute zur Goldmedaille getragen. Jetzt habe ich mein zweites Gold.Ich wusste, dass ich heute alles geben muss um hier zu gewinnen , und bin deshalb sehr, sehr zufrieden und gl\u00fccklich.\u201c Therese Johaug.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<blockquote><p>Diese Leistungen sind f\u00fcr uns alle sehr entt\u00e4uschend, zumal wir uns f\u00fcr heute eine Medaille erhofft hatten.\u201c Jelena V\u00e4lbe, Pr\u00e4sidentin Russischer Skiverband<\/p><\/blockquote>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Wer will diese Therese Johaug eigentlich bei der WM in Seefeld schlagen? Unter den Augen des Norwegischen K\u00f6nigs Harald , aber auch unter denen des Schwedischen K\u00f6nigs Carl &#8211; Gustav l\u00e4uft Therese Johaug erneut zu Gold,und gewinnt auch die 10 Km Individal im klassischen Stil der Damen, und damit ihre zweite Goldmedaille. Die Silbermedaille ging [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":516,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9,26],"class_list":["post-515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-langlauf","tag-wm-seefeld-2019"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=515"}],"version-history":[{"count":1,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/515\/revisions"}],"predecessor-version":[{"id":517,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/515\/revisions\/517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/516"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}