{"id":496,"date":"2019-02-23T20:15:50","date_gmt":"2019-02-23T20:15:50","guid":{"rendered":"http:\/\/wintersport.news\/?p=496"},"modified":"2019-02-24T20:16:17","modified_gmt":"2019-02-24T20:16:17","slug":"wm-seefeld-2019-deutscher-doppelsieg-im-skispringen-markus-eisenbichler-neuer-weltmeister-kamil-stoch-auf-platz-fuenf","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/wm-seefeld-2019-deutscher-doppelsieg-im-skispringen-markus-eisenbichler-neuer-weltmeister-kamil-stoch-auf-platz-fuenf\/","title":{"rendered":"WM Seefeld 2019: Deutscher Doppelsieg im Skispringen &#8211; Markus Eisenbichler neuer Weltmeister &#8211; Kamil Stoch auf Platz f\u00fcnf"},"content":{"rendered":"<p>Das war geballte Freude, des neuen Skisprung Weltmeisters Markus Eisenbichler.Mit seinem ersten Sieg in einem Einzelwettbewerb gewinnt er WM Gold vor seinem Mannschaftskameraden Karl Geiger, der Vize-Weltmeister wird \u00a0und Silber gewann. Kilian Peier aus der Schweiz gewinnt \u00fcberraschend die Bronzemedaille.<\/p>\n<div>\n<p>Mitfavorit Kamil Stoch kam \u00fcber den f\u00fcnften Platz nicht hinaus, Dawid Kubacki wurde zw\u00f6lfter.<\/p>\n<div><\/div>\n<div>Ergebnisse Skispringen WM Seefeld HS 130:<\/div>\n<div><\/div>\n<div>1. Markus Eisenbichler, GER \u00a0 \u00a0 \u00a0 \u00a0279,4 Punkte<\/div>\n<div>2. Karl Geiger, GER \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 267,3 Punkte<\/div>\n<div>3. Kilian Peier, SUI \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0266,1 Punkte<\/div>\n<div>.<\/div>\n<div>5. Kamil Stoch,POL \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0259,4 Punkte<\/div>\n<div>12. Dawid Kubacki, POL \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0240,2 Punkte<\/div>\n<div><\/div>\n<blockquote>\n<div><\/div>\n<div>Ich habe das Springen heute im ersten Durchgang vergeigt. Mit meinem zweiten Sprung konnte ich noch einige Pl\u00e4tze gutmachen- leider hat es nicht mehr zu einer Medaille gelangt.\u201c\u00a0Kamil Stoch<\/div>\n<\/blockquote>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das war geballte Freude, des neuen Skisprung Weltmeisters Markus Eisenbichler.Mit seinem ersten Sieg in einem Einzelwettbewerb gewinnt er WM Gold vor seinem Mannschaftskameraden Karl Geiger, der Vize-Weltmeister wird \u00a0und Silber gewann. Kilian Peier aus der Schweiz gewinnt \u00fcberraschend die Bronzemedaille. Mitfavorit Kamil Stoch kam \u00fcber den f\u00fcnften Platz nicht hinaus, Dawid Kubacki wurde zw\u00f6lfter. Ergebnisse [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[7,26],"class_list":["post-496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-skispringen","tag-wm-seefeld-2019"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=496"}],"version-history":[{"count":2,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/496\/revisions"}],"predecessor-version":[{"id":500,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/496\/revisions\/500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/497"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}