{"id":488,"date":"2019-02-23T14:17:53","date_gmt":"2019-02-23T14:17:53","guid":{"rendered":"http:\/\/wintersport.news\/?p=488"},"modified":"2019-02-23T14:20:19","modified_gmt":"2019-02-23T14:20:19","slug":"wm-seefeld-2019-skiathlon-johaug-nicht-zu-schlagen-neprayeva-gewinnt-die-bronzemedaille","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/wm-seefeld-2019-skiathlon-johaug-nicht-zu-schlagen-neprayeva-gewinnt-die-bronzemedaille\/","title":{"rendered":"WM Seefeld 2019: Skiathlon: Johaug nicht zu schlagen &#8211; Neprayeva gewinnt die Bronzemedaille"},"content":{"rendered":"<div>Bei der Nordischen Ski- WM feierte Therese Johaug \u00fcber 7,5 Km klassisch und im 7,5 Km freien Stil einen souver\u00e4nen Sieg. Die nun achtmalige Weltmeisterin ist in diesem Winter die alles \u00fcberragende Athletin, und wird bei dieser WM nur schwer \u00a0zu schlagen sein. Silber sicherte sich ihre Landsfrau Ingvild Flugstad \u00d6stberg,Bronze ging an die Russin Natalia Nprayeva.<\/div>\n<div><\/div>\n<div>Ergebnisse Ladies Skiathlon 15 Km Free:<\/div>\n<div><\/div>\n<div>1. Therese JohauG, NOR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 36.54,5 Min.<\/div>\n<div>2. Ingvild Flugstad \u00d6stberg,NOR \u00a0 \u00a0 \u00a0 + 57,6 Sek.<\/div>\n<div>3. Natalia Naprayeva, RUS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0+ 58,7 Sek.<\/div>\n<div><\/div>\n<blockquote>\n<div>Ich wollte heute um eine Medaille mitk\u00e4mpfen, und konnte das hohe Tempo gut mitgehen.Irgendwann im Laufe des Rennens mussten wir abrei\u00dfen lassen, da Therese einfach nicht zu stoppen war. Da gab e f\u00fcr mich nur noch die Devise- eine Medaille zu gewinnen, egal welche, und nun darf ich mich \u00fcber Bronze freuen.\u201c\u00a0Natalia Neprayeva<\/div>\n<\/blockquote>\n<div><\/div>\n<div><\/div>","protected":false},"excerpt":{"rendered":"<p>Bei der Nordischen Ski- WM feierte Therese Johaug \u00fcber 7,5 Km klassisch und im 7,5 Km freien Stil einen souver\u00e4nen Sieg. Die nun achtmalige Weltmeisterin ist in diesem Winter die alles \u00fcberragende Athletin, und wird bei dieser WM nur schwer \u00a0zu schlagen sein. Silber sicherte sich ihre Landsfrau Ingvild Flugstad \u00d6stberg,Bronze ging an die Russin [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":489,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9,26],"class_list":["post-488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-langlauf","tag-wm-seefeld-2019"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=488"}],"version-history":[{"count":2,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/488\/revisions"}],"predecessor-version":[{"id":495,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/488\/revisions\/495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/489"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}