{"id":3704,"date":"2022-02-24T12:20:00","date_gmt":"2022-02-24T12:20:00","guid":{"rendered":"https:\/\/wintersport.news\/?p=3704"},"modified":"2022-02-24T12:24:55","modified_gmt":"2022-02-24T12:24:55","slug":"fuenf-finger-einer-erfolgs-geschichte","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/fuenf-finger-einer-erfolgs-geschichte\/","title":{"rendered":"F\u00fcnf Finger einer Erfolgs-Geschichte"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3704\" class=\"elementor elementor-3704\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5a2930 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5a2930\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a26a8da\" data-id=\"a26a8da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a82f96c elementor-widget elementor-widget-text-editor\" data-id=\"a82f96c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sitzt, passt, wackelt und hat Luft! Die Olympischen Spiele in Peking sind schon wieder Geschichte. Es waren besondere Spiele in vielerlei Hinsicht, dominiert von der Corona Pandemie, politisch \u00fcberfrachtet, gesch\u00fcttelt von einem Skandal um ein 15j\u00e4hriges M\u00e4dchen im Eiskunstlauf, eingegrenzt durch den Zuschauerausschluss, eingeschr\u00e4nkt auch durch die \u201eclosed loops\u201c oder \u201ebubbles\u201c, wie die speziell f\u00fcr die Olympiateilnehmer vorgesehenen Zonen genannt wurden, in denen sich wegen der Spiele nach China gereiste Personen bewegen mussten. Es waren aber auch perfekt organisierte Spiele, fast fehlerlos im administrativen Bereich, mit hochmodernen, architektonisch beeindruckenden Sportst\u00e4tten, mit vorzeigbaren Unterk\u00fcnften. Vor allem aber verbunden mit dem Fakt, dass das viel kritisierte Kontrollsystem in Sachen Corona Fr\u00fcchte trug, es gab innerhalb der Olympischen Familie praktisch keine Neuansteckungen.<\/p><p>Daf\u00fcr aber leider einige F\u00e4lle bei Einreise. Die Prominentesten wohl in der Nordischen Kombination. Kristian Ilves aus Estland, Eric Frenzel und Terence Weber und \u00dcberflieger Jarl Magnus Riiber aus Norwegen &#8211; gleich vier Athleten aus den Top-Sieben der Weltrangliste mussten passen, entweder komplett oder zumindest teilweise.<\/p><p>Daf\u00fcr sprangen andere in die Bresche. Joergen Graabak beispielsweise, der gleich 2x Gold gewann. Er war damit der erfolgreichste Kombinierer der Tage von Peking, mit insgesamt 4x Gold ist er einer der erfolgreichsten Medaillensammler, in Sachen Gold sogar der einzige Winterzweik\u00e4mpfer, der vier Goldene sein Eigen nennen darf.<\/p><p>Vier Goldene, die hat auch Johannes Thingnes Boe auf der Habenseite, allerdings alleine bei diesen Spielen errungen. Insgesamt steht der Norweger bei f\u00fcnf Siegen, schlie\u00dflich gewann er in Pyeongchang vor vier Jahren auch schon die Einzelkonkurrenz. Boe ist der Biathlon-K\u00f6nig von China, schaffte es dabei auch, die Angriffe von Quentin Fillon Maillet abzuwehren, der aber ebenfalls zufrieden von den Spielen nach Hause fahren darf.<\/p><p>Der Langlauf-Zar kommt aus Russland und hei\u00dft Alexander Bolschunov. Jahrelang hatte der 25-j\u00e4hrige im Duell mit Norwegens Johannes Hoesflot Klaebo meist knapp das Nachsehen. In China drehte er den Spie\u00df um und sammelte drei Goldmedaillen ein, in beeindruckender Weise \u00fcbrigens. So wie Marte Olsbu Roiseland, die im Biathlon brillierte und im Gegensatz zu vielen anderen Sportlerinnen und Sportlern auch dem nervlichen Druck standhielt, als Favoritin der Erwartungshaltung gerecht zu werden.<\/p><p>Man k\u00f6nnte andere Sportlerinnen und Sportler nennen, es gab nat\u00fcrlich auch Misserfolge und Entt\u00e4uschungen. Und es gab \u00dcberraschungen, den Teamsprint der Langlauffrauen mit dem Erfolg des deutschen Duos, die Dominanz in der Eisrinne bei Rodel-, Bob- und Skeleton-Entscheidungen. Und es gab einen Olympiasieg, der speziell in Norwegen f\u00fcr unglaubliches Aufsehen sorgte. Auf der Gro\u00dfschanze gewann n\u00e4mlich Marius Lindvik. Gut, m\u00f6chte man meinen, Lindvik also, fein. Aber: Es war f\u00fcr die Norweger die erste Goldmedaille von der Gro\u00dfschanze. 1964 hatte man zum ersten Mal zwei Entscheidungen, gab es den Unterschied zwischen Normalschanze und dem gro\u00dfen Bakken. Zum Auftakt siegte 1964 Toralf Engan, danach nie wieder ein Norweger &#8211; zumindest nicht von dieser Schanze. In Peking war es endlich wieder soweit und f\u00fcr ein Land, dass sich &#8211; nicht v\u00f6llig zu Unrecht &#8211; als Erfinder der Sportart sieht, war das die vielleicht sch\u00f6nste Goldmedaille dieser Spiele.<\/p><p>Ganz nebenbei: Keiner der Superstars dieser Olympischen Spiele, ob nun aus Russland, Frankreich oder Norwegen hatte trotz der eisigen Temperaturen Probleme mit der K\u00e4lte an H\u00e4nden oder Fingern. Was erfreulich ist, denn es ist die Summe der kleinen Dinge, die zum Erfolg beitragen.<\/p><p>\u00a0<\/p><p>Pictures: K. Voigt Fotografie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sitzt, passt, wackelt und hat Luft! Die Olympischen Spiele in Peking sind schon wieder Geschichte. Es waren besondere Spiele in vielerlei Hinsicht, dominiert von der Corona Pandemie, politisch \u00fcberfrachtet, gesch\u00fcttelt von einem Skandal um ein 15j\u00e4hriges M\u00e4dchen im Eiskunstlauf, eingegrenzt durch den Zuschauerausschluss, eingeschr\u00e4nkt auch durch die \u201eclosed loops\u201c oder \u201ebubbles\u201c, wie die speziell f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,30],"tags":[],"class_list":["post-3704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog_wintersport_insights"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/3704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=3704"}],"version-history":[{"count":6,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/3704\/revisions"}],"predecessor-version":[{"id":3711,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/3704\/revisions\/3711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/3710"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=3704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=3704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=3704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}