{"id":363,"date":"2019-01-29T07:32:49","date_gmt":"2019-01-29T07:32:49","guid":{"rendered":"http:\/\/wintersport.news\/?p=363"},"modified":"2019-01-29T07:32:49","modified_gmt":"2019-01-29T07:32:49","slug":"fanqi-meng-junioren-weltmeisterin-in-osrible","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/fanqi-meng-junioren-weltmeisterin-in-osrible\/","title":{"rendered":"Fanqi Meng Junioren Weltmeisterin in Osrible"},"content":{"rendered":"<p>Zum Auftakt der Biathlon Junioren &#8211; WM im slowakischen Osrible sind die ersten WM-Medaillen vergeben. Im 12,5 Km Einzelrennen der Juniorinnen ging der Weltmeister Titel an Fanqi Meng aus China. Die alles \u00fcberragende Athletin verwies mit einem R\u00fcckstand von 1.08,0 Minuten Juliane Fr\u00fchwirt und Franziska Pfn\u00fcr mit 1.35,8 Minuten auf die Silber- und Bronzepl\u00e4tze.<\/p>\n<p>&nbsp;<\/p>\n<p>Ergebnisse Biathlon Junioren WM, Osrible:<\/p>\n<p>12,5 Km Einzel Juniorinnen:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Fanqi Meng, CHN 40.06,7 Min.<\/li>\n<li>Juliane Fr\u00fchwirt, GER\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0+ 1.08,0 Sek.<\/li>\n<li>Franziska Pfn\u00fcr, GER + 1.35,8 Sek.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-365\" src=\"http:\/\/wintersport.news\/wp-content\/uploads\/2019\/01\/IMG_1673.png\" alt=\"\" width=\"360\" height=\"640\" srcset=\"https:\/\/wintersport.news\/wp-content\/uploads\/2019\/01\/IMG_1673.png 360w, https:\/\/wintersport.news\/wp-content\/uploads\/2019\/01\/IMG_1673-169x300.png 169w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Dieser Weltmeister Titel bedeutet sehr viel f\u00fcr uns und hat gezeigt, dass unsere guten Leistungen im Weltcup nicht von ungef\u00e4hr sind und Gewicht haben. Wenn\u201c Funny\u201c weiterhin so an sich arbeitet, wird man in Zukunft noch viel von ihr h\u00f6ren. Wir alle im Verband und im Team sind sehr stolz und happy auf diese Leistung.\u201c Nationaltrainer Joe Obererlacher<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Zum Auftakt der Biathlon Junioren &#8211; WM im slowakischen Osrible sind die ersten WM-Medaillen vergeben. Im 12,5 Km Einzelrennen der Juniorinnen ging der Weltmeister Titel an Fanqi Meng aus China. Die alles \u00fcberragende Athletin verwies mit einem R\u00fcckstand von 1.08,0 Minuten Juliane Fr\u00fchwirt und Franziska Pfn\u00fcr mit 1.35,8 Minuten auf die Silber- und Bronzepl\u00e4tze. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":364,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6,24],"class_list":["post-363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-biathlon","tag-junioren"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":1,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/363\/revisions"}],"predecessor-version":[{"id":366,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/363\/revisions\/366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/364"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}