{"id":319,"date":"2019-01-20T19:10:14","date_gmt":"2019-01-20T19:10:14","guid":{"rendered":"http:\/\/wintersport.news\/?p=319"},"modified":"2019-01-20T19:10:14","modified_gmt":"2019-01-20T19:10:14","slug":"julian-eberhard-wieder-zweiter-im-massenstart","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/julian-eberhard-wieder-zweiter-im-massenstart\/","title":{"rendered":"Julian Eberhard wieder Zweiter im Massenstart"},"content":{"rendered":"<p>Bei Kaiserwetter in der Ruhpoldinger Chiemgau Arena und perfekten \u00e4u\u00dferen Bedingungen war Johannes Thingnes Boe \u00a0der Sieg im 15 Km Massenstart Rennen der Herren nicht zu nehmen. In einem taktisch eingeteilten Rennen war er wieder einmal nicht zu schlagen und siegte in einem spannenden Schlussspurt vor Julian Eberhard und Quentin Fillon Maillet. Platz vier ging an Martin Fourcade.<\/p>\n<div><\/div>\n<div>Ergebnisse 15 Km Massenstart Herren, Ruhpolding:<\/div>\n<div>.<\/div>\n<div><\/div>\n<div><\/div>\n<div>1. Johannes Thingnes Boe, NOR \u00a0 \u00a0 \u00a036.43,8 Min.<\/div>\n<div>2. Julian Eberhard, AUT \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 + 0,6 Sek.<\/div>\n<div>3. Quentin Fillon-Mailett, FRA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 + 2,8 Sek.<\/div>\n<div>.<\/div>\n<div>4. Martin Fourcade, FRA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0+ 8,4 Sek.<\/div>\n<div>.<\/div>\n<div><\/div>\n<blockquote>\n<div>Ich habe mir das Rennen heute klug eingeteilt. Es hat sehr viel Spass gemacht vor solch einer Kulisse zu laufen. Der zweite Platz hier &#8211; gewaltig. Ich bin einfach nur happy und sehr zufrieden heute.Ein spannendes Rennen bis zum Schluss.\u201c Julian Eberhard<\/div>\n<\/blockquote>\n<div>Foto: Matthias Schrader<\/div>","protected":false},"excerpt":{"rendered":"<p>Bei Kaiserwetter in der Ruhpoldinger Chiemgau Arena und perfekten \u00e4u\u00dferen Bedingungen war Johannes Thingnes Boe \u00a0der Sieg im 15 Km Massenstart Rennen der Herren nicht zu nehmen. In einem taktisch eingeteilten Rennen war er wieder einmal nicht zu schlagen und siegte in einem spannenden Schlussspurt vor Julian Eberhard und Quentin Fillon Maillet. Platz vier ging [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":320,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6,21],"class_list":["post-319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-biathlon","tag-ruhpolding"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":1,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"predecessor-version":[{"id":321,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/319\/revisions\/321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/320"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}