{"id":1721,"date":"2020-11-26T11:10:01","date_gmt":"2020-11-26T11:10:01","guid":{"rendered":"https:\/\/wintersport.news\/?p=1721"},"modified":"2020-11-26T11:14:07","modified_gmt":"2020-11-26T11:14:07","slug":"skispringen-trommeln-im-wald","status":"publish","type":"post","link":"https:\/\/wintersport.news\/en\/skispringen-trommeln-im-wald\/","title":{"rendered":"Skisprung Auftakt: Trommeln im Wald"},"content":{"rendered":"<p><strong>Alles neu oder alles wie immer? Sp\u00e4testens als im August die Skispringer im polnischen Wisla Station machten, zu einem Wettkampf, der normalerweise unter dem Namen \u201eSommer-Grand-Prix\u201c firmiert, durften sich die Beobachter die Frage mit einem konsequenten \u201eSowohl als auch\u201c beantworten.<\/strong><\/p>\n<p>Gut wie immer waren die Gastgeber, auch die Spr\u00fcnge selbst sahen nicht anders aus als in den Jahren zuvor. Und doch war alles irgendwie komisch. Weil die Fans fast v\u00f6llig fehlten, weil Abst\u00e4nde eingehalten, Masken getragen werden mussten, weil man Fotografen und schreibende Journalisten mit der Lupe suchen musste und weil ein gro\u00dfer Teil der weltbesten Springer die Reise in die schlesischen Beskiden gar nicht erst angetreten hatte. Schlie\u00dflich war das Wochenende im August die einzige Vergleichsm\u00f6glichkeit, statt Sommer-Grand-Prix gab es diesen einen Wettkampf und sonst nichts. COVID 19 hatte den Sport beeinflusst.<\/p>\n<p>Ein Vierteljahr sp\u00e4ter waren dann wenigstens alle Springer da, denn Wisla ist seit geraumer Zeit die erste Station des Weltcup-Winters. Aber ansonsten musste man konstatieren: Die Bedingungen waren eher noch schlechter geworden. Denn die Pandemie-Situation in Europa hatte sich im Vergleich zum Sommer zugespitzt, einige L\u00e4nder Lockdowns verh\u00e4ngt, fast alle die Kontaktm\u00f6glichkeiten erheblich eingeschr\u00e4nkt. Mit den entsprechenden Auswirkungen auf den Sport. Denn nun waren gar keine Zuschauer vor Ort. Oder? Als am Samstag zur Mannschaftskonkurrenz geblasen wurde, stand zwar kein Besucher im riesigen Schanzenareal. Leere Trib\u00fcnen, ein leeres Stadion \u2013 Tristesse pur. Doch als der erste polnische Springer im Mannschaftswettbewerb auf den Balken kletterte, um sich auf seinen Sprung vorzubereiten, da wurde es pl\u00f6tzlich laut. Trommeln waren zu h\u00f6ren, Tr\u00f6ten, Jubelschreie, Anfeuerungsrufe. Und w\u00e4hrend einige Fernsehzuschauer noch r\u00e4tselten, ob die polnischen Gastgeber den Ger\u00e4uschpegel via Lautsprecher einblenden w\u00fcrden \u2013 so wie das der eine oder andere Fernsehsender beim Fu\u00dfball versucht \u2013 da beantworteten ein paar Kameraeinstellungen die Frage nach der Ursache des L\u00e4rms. Denn urpl\u00f6tzlich waren aus dem Wald rund um die Schanze einige Fans herausgetreten, geschm\u00fcckt mit Fahnen und Schals in den polnischen Nationalfarben. Und die feuerten ihre Jungs an. Das Prozedere wiederholte sich im ersten Durchgang immer dann, wenn ein Athlet des Gastgeberlandes aufgerufen wurde. Besonders heftig bejubelt wurden Vierschanzentourneesieger David Kubacki und der Liebling der Nation, Kamil Stoch. Auch am Sonntag, als die Einzelkonkurrenz gestartet wurde, konnte man den spontanen Jubel am Rande der Schanze wieder erleben.<\/p>\n<p>M\u00f6glicherweise waren diese Aktionen nicht im Sinne der Beh\u00f6rden, denn sie konterkarierten das Bestreben nach m\u00f6glichst wenig Kontakten. Aus Sicht der Springer und der Fans vor dem Fernseher aber vermittelte der Spontan-Applaus aber wenigstens f\u00fcr ein paar Momente das Gef\u00fchl, nicht bei einem Trainingsspringen zuzuschauen. Und erinnerte daran, wie wichtig die Fans f\u00fcr den Sport sind.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alles neu oder alles wie immer? Sp\u00e4testens als im August die Skispringer im polnischen Wisla Station machten, zu einem Wettkampf, der normalerweise unter dem Namen \u201eSommer-Grand-Prix\u201c firmiert, durften sich die Beobachter die Frage mit einem konsequenten \u201eSowohl als auch\u201c beantworten. Gut wie immer waren die Gastgeber, auch die Spr\u00fcnge selbst sahen nicht anders aus als [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1722,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,30],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog_wintersport_insights"],"_links":{"self":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":2,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":1726,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/posts\/1721\/revisions\/1726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media\/1722"}],"wp:attachment":[{"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wintersport.news\/en\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}